{"id":325,"count":3,"description":"","link":"https:\/\/www.monetupasaulis.lt\/en\/product-category\/pagal-valstybe-en\/canada\/","name":"Canada","slug":"canada","taxonomy":"product_cat","parent":274,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Canada Archives - monetupasaulis.lt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.monetupasaulis.lt\/en\/product-category\/pagal-valstybe-en\/canada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canada Archives - monetupasaulis.lt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.monetupasaulis.lt\/en\/product-category\/pagal-valstybe-en\/canada\/\" \/>\n<meta property=\"og:site_name\" content=\"monetupasaulis.lt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.monetupasaulis.lt\\\/en\\\/product-category\\\/pagal-valstybe-en\\\/canada\\\/\",\"url\":\"https:\\\/\\\/www.monetupasaulis.lt\\\/en\\\/product-category\\\/pagal-valstybe-en\\\/canada\\\/\",\"name\":\"Canada Archives - monetupasaulis.lt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.monetupasaulis.lt\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.monetupasaulis.lt\\\/en\\\/product-category\\\/pagal-valstybe-en\\\/canada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.monetupasaulis.lt\\\/en\\\/product-category\\\/pagal-valstybe-en\\\/canada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"GSP Investment\",\"item\":\"https:\\\/\\\/www.monetupasaulis.lt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.monetupasaulis.lt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.monetupasaulis.lt\\\/en\\\/\",\"name\":\"monetupasaulis.lt\",\"description\":\"Monetu pasaulis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.monetupasaulis.lt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canada Archives - monetupasaulis.lt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.monetupasaulis.lt\/en\/product-category\/pagal-valstybe-en\/canada\/","og_locale":"en_US","og_type":"article","og_title":"Canada Archives - monetupasaulis.lt","og_url":"https:\/\/www.monetupasaulis.lt\/en\/product-category\/pagal-valstybe-en\/canada\/","og_site_name":"monetupasaulis.lt","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.monetupasaulis.lt\/en\/product-category\/pagal-valstybe-en\/canada\/","url":"https:\/\/www.monetupasaulis.lt\/en\/product-category\/pagal-valstybe-en\/canada\/","name":"Canada Archives - monetupasaulis.lt","isPartOf":{"@id":"https:\/\/www.monetupasaulis.lt\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.monetupasaulis.lt\/en\/product-category\/pagal-valstybe-en\/canada\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.monetupasaulis.lt\/en\/product-category\/pagal-valstybe-en\/canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"GSP Investment","item":"https:\/\/www.monetupasaulis.lt\/en\/"},{"@type":"ListItem","position":2,"name":"Canada"}]},{"@type":"WebSite","@id":"https:\/\/www.monetupasaulis.lt\/en\/#website","url":"https:\/\/www.monetupasaulis.lt\/en\/","name":"monetupasaulis.lt","description":"Monetu pasaulis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.monetupasaulis.lt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.monetupasaulis.lt\/en\/wp-json\/wp\/v2\/product_cat\/325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monetupasaulis.lt\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.monetupasaulis.lt\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.monetupasaulis.lt\/en\/wp-json\/wp\/v2\/product_cat\/274"}],"wp:post_type":[{"href":"https:\/\/www.monetupasaulis.lt\/en\/wp-json\/wp\/v2\/product?product_cat=325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}